{"id":319,"date":"2019-09-02T16:48:31","date_gmt":"2019-09-02T14:48:31","guid":{"rendered":"https:\/\/insurtech.services\/?p=319"},"modified":"2019-09-02T16:48:48","modified_gmt":"2019-09-02T14:48:48","slug":"insurtech-group-preis-an-die-jahrgangsbesten-informatiker-verliehen","status":"publish","type":"post","link":"https:\/\/insurtech.services\/en\/insurtech-group-preis-an-die-jahrgangsbesten-informatiker-verliehen\/","title":{"rendered":"insurtech.group-Preis an die jahrgangsbesten Informatiker verliehen"},"content":{"rendered":"\t\t<div data-elementor-type=\"wp-post\" data-elementor-id=\"319\" class=\"elementor elementor-319 elementor-1\" data-elementor-post-type=\"post\">\n\t\t\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-432a48d elementor-section-height-min-height elementor-section-boxed elementor-section-height-default elementor-section-items-middle\" data-id=\"432a48d\" data-element_type=\"section\" data-e-type=\"section\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-d6ee6a9\" data-id=\"d6ee6a9\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-1c99991 elementor-widget elementor-widget-heading\" data-id=\"1c99991\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.base\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h1 class=\"h3 text-white\">insurtech.group-Preis an die jahrgangsbesten Informatiker verliehen<\/h1>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-416f4b1 elementor-widget__width-auto elementor-widget elementor-widget-heading\" data-id=\"416f4b1\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.base\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h3 class=\"text-label text-cyan\">2. September 2019<\/h3>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-784c424 elementor-widget__width-auto elementor-widget elementor-widget-heading\" data-id=\"784c424\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.base\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h3 class=\"text-label text-cyan\">16:48<\/h3>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-a433d9e elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"a433d9e\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-c2ec669\" data-id=\"c2ec669\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-3e3300b elementor-widget elementor-widget-text-editor\" data-id=\"3e3300b\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.base\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t        <p class=\"elementor-text-editor elementor-clearfix text-primary\">Wie jedes Jahr feierten die Absolventen des Fachbereichs Informatik und Mathematik der Goethe-Universit\u00e4t Frankfurt am Ende des Semesters ihren erfolgreichen Studienabschluss. Das Dekanat lud hierzu am 12.07.2019 alle Abg\u00e4nger, ihre Familien und G\u00e4ste, sowie Mitglieder des Fachbereichs zu einer kleinen Feier in den Casino-Saal am Westend-Campus ein. Dort versammelten sich am Abend mehr als 350 frischgebackene Akademiker der Studieng\u00e4nge Informatik, Bioinformatik, Wirtschaftsinformatik, sowie Mathematik um sich Ihre Bachelor- und Master-Urkunden \u00fcberreichen zu lassen.\nBegonnen wurden die Feierlichkeiten mit einer Begr\u00fc\u00dfungsrede von Dekan Prof. Dr.-Ing. Lars Hedrich. Im Anschluss daran bekamen die Absolventen feierlich ihre verdienten Abschlussdiplome vergeben.\n<br>\n<br>\nNach der Hauptzeremonie wurden die Jahrgangbesten auf die B\u00fchne gebeten, um ihre herausragenden Leistungen zu ehren. Im Zuge dessen wurde dieses Jahr zum ersten Mal der insurtech.group-Preis verliehen. Die mit jeweils 500 Euro dotierte Auszeichnung wird an die beiden Jahrgangsbesten aus dem Masterstudiengang Informatik vergeben. Die insurtech.group GmbH will den Absolventen mit dieser Ehrung zeigen, dass Leistung belohnt und besonderer Einsatz bemerkt wird.\nHierzu Andreas Maile, Gesch\u00e4ftsf\u00fchrer der insurtech.group GmbH: \u201eIm Hinblick auf den herrschenden Fachkr\u00e4ftemangel ist es uns besonders wichtig ein Zeichen zu setzen und klar zu machen, dass diesem nur mit engagierter Nachwuchsf\u00f6rderung zu begegnen ist. Uns liegt viel daran mit gutem Beispiel voran zu gehen und die Insurtech Branche am Standort Frankfurt zu st\u00e4rken und weiterzuentwickeln. Der insurtech.group-Preis ist nur einer von vielen Schritten in diese Richtung.\u201c<\/p>\n        \t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-5fbf3b8 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"5fbf3b8\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-47cb037\" data-id=\"47cb037\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-df22118 elementor-widget elementor-widget-image\" data-id=\"df22118\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img fetchpriority=\"high\" decoding=\"async\" width=\"300\" height=\"200\" src=\"https:\/\/insurtech.services\/wp-content\/uploads\/2019\/08\/insurtech_group_preisverleihung_2019_web-1-300x200.jpg\" class=\"attachment-large size-large wp-image-320\" alt=\"\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-10aa051 elementor-widget elementor-widget-heading\" data-id=\"10aa051\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.base\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<span class=\"text-small\">Preistr\u00e4ger des insurtech.group-Preises<\/span>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-0aec512 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"0aec512\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-71ed1de\" data-id=\"71ed1de\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-3978108 elementor-widget elementor-widget-text-editor\" data-id=\"3978108\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.base\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t        <p class=\"elementor-text-editor elementor-clearfix text-primary\">Dieses Jahr erhielten Niklas Hahn und Eric Hutter (auf dem Foto mit Dekan Prof. Dr.-Ing. Lars Hedrich) die Auszeichnung f\u00fcr Ihre exzellenten Abschlussarbeiten. Wir gratulieren ihnen zu ihrem au\u00dferordentlichen Erfolg und w\u00fcnschen ihnen alles Gute auf ihrem beruflichen Weg.<\/p>\n        \t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<\/div>\n\t\t","protected":false},"excerpt":{"rendered":"<p>Wie jedes Jahr feierten die Absolventen des Fachbereichs Informatik und Mathematik der Goethe-Universit\u00e4t Frankfurt am Ende des Semesters ihren erfolgreichen Studienabschluss. Das Dekanat lud hierzu am 12.07.2019 alle Abg\u00e4nger, ihre Familien und G\u00e4ste, sowie Mitglieder des Fachbereichs zu einer kleinen Feier in den Casino-Saal am Westend-Campus ein. Dort versammelten sich am Abend mehr als 350 [&hellip;]<\/p>\n","protected":false},"author":2,"featured_media":314,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[10],"tags":[],"class_list":["post-319","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-uncategorized"],"_links":{"self":[{"href":"https:\/\/insurtech.services\/en\/wp-json\/wp\/v2\/posts\/319","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/insurtech.services\/en\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/insurtech.services\/en\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/insurtech.services\/en\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/insurtech.services\/en\/wp-json\/wp\/v2\/comments?post=319"}],"version-history":[{"count":2,"href":"https:\/\/insurtech.services\/en\/wp-json\/wp\/v2\/posts\/319\/revisions"}],"predecessor-version":[{"id":322,"href":"https:\/\/insurtech.services\/en\/wp-json\/wp\/v2\/posts\/319\/revisions\/322"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/insurtech.services\/en\/wp-json\/wp\/v2\/media\/314"}],"wp:attachment":[{"href":"https:\/\/insurtech.services\/en\/wp-json\/wp\/v2\/media?parent=319"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/insurtech.services\/en\/wp-json\/wp\/v2\/categories?post=319"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/insurtech.services\/en\/wp-json\/wp\/v2\/tags?post=319"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}